{"id":16002,"date":"2016-12-02T09:00:44","date_gmt":"2016-12-02T08:00:44","guid":{"rendered":"https:\/\/wordpress-763711-2606952.cloudwaysapps.com\/?p=16002"},"modified":"2016-12-01T23:13:27","modified_gmt":"2016-12-01T22:13:27","slug":"vitali-inaugura-parco-commerciale-san-giuliano-milanese","status":"publish","type":"post","link":"https:\/\/www.investinitalyrealestate.com\/it\/vitali-inaugura-parco-commerciale-san-giuliano-milanese\/","title":{"rendered":"Vitali inaugura nuovo parco commerciale a San Giuliano Milanese"},"content":{"rendered":"<p>Il Gruppo Vitali, primaria societ\u00e0 di costruzioni italiane, inaugura un nuovo parco commerciale a San Giuliano Milanese, nell&#8217;hinterland di Milano. <\/p>\n<p>L\u2019intervento si sviluppa su una superficie complessiva di oltre 20.000 mq ed \u00e8 stato costruito in tempi record, meno di 9 mesi dalla posa della prima pietra al taglio del nastro. <\/p>\n<p>Il nuovo parco commerciale \u00e8 stato realizzato in collaborazione con Obi e Burger King.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il Gruppo Vitali, primaria societ\u00e0 di costruzioni italiane, inaugura un nuovo parco commerciale a San Giuliano Milanese, nell&#8217;hinterland di Milano. L\u2019intervento si sviluppa su una superficie complessiva di oltre 20.000 mq ed \u00e8 stato costruito in tempi record, meno di 9 mesi dalla posa della prima pietra al taglio del nastro. Il nuovo parco commerciale [&hellip;]<\/p>\n","protected":false},"author":462,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[366],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Vitali inaugura nuovo parco commerciale a San Giuliano Milanese - ICE - Italian Trade Agency<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.investinitalyrealestate.com\/it\/vitali-inaugura-parco-commerciale-san-giuliano-milanese\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vitali inaugura nuovo parco commerciale a San Giuliano Milanese - ICE - Italian Trade Agency\" \/>\n<meta property=\"og:description\" content=\"Il Gruppo Vitali, primaria societ\u00e0 di costruzioni italiane, inaugura un nuovo parco commerciale a San Giuliano Milanese, nell&#8217;hinterland di Milano. L\u2019intervento si sviluppa su una superficie complessiva di oltre 20.000 mq ed \u00e8 stato costruito in tempi record, meno di 9 mesi dalla posa della prima pietra al taglio del nastro. Il nuovo parco commerciale [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.investinitalyrealestate.com\/it\/vitali-inaugura-parco-commerciale-san-giuliano-milanese\/\" \/>\n<meta property=\"og:site_name\" content=\"ICE - Italian Trade Agency\" \/>\n<meta property=\"article:published_time\" content=\"2016-12-02T08:00:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-12-01T22:13:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.investinitalyrealestate.com\/wp-content\/uploads\/2016\/02\/social-home.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"628\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Vittorio Zirnstein\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.investinitalyrealestate.com\/it\/#website\",\"url\":\"https:\/\/www.investinitalyrealestate.com\/it\/\",\"name\":\"ICE - Italian Trade Agency\",\"description\":\"Piattaforma per la vendita degli immobili pubblici Italiani\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.investinitalyrealestate.com\/it\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.investinitalyrealestate.com\/it\/vitali-inaugura-parco-commerciale-san-giuliano-milanese\/#webpage\",\"url\":\"https:\/\/www.investinitalyrealestate.com\/it\/vitali-inaugura-parco-commerciale-san-giuliano-milanese\/\",\"name\":\"Vitali inaugura nuovo parco commerciale a San Giuliano Milanese - ICE - Italian Trade Agency\",\"isPartOf\":{\"@id\":\"https:\/\/www.investinitalyrealestate.com\/it\/#website\"},\"datePublished\":\"2016-12-02T08:00:44+00:00\",\"dateModified\":\"2016-12-01T22:13:27+00:00\",\"author\":{\"@id\":\"https:\/\/www.investinitalyrealestate.com\/it\/#\/schema\/person\/d945b942fb6a7f2fa67a4689e376551d\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.investinitalyrealestate.com\/it\/vitali-inaugura-parco-commerciale-san-giuliano-milanese\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.investinitalyrealestate.com\/it\/vitali-inaugura-parco-commerciale-san-giuliano-milanese\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.investinitalyrealestate.com\/it\/vitali-inaugura-parco-commerciale-san-giuliano-milanese\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.investinitalyrealestate.com\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vitali inaugura nuovo parco commerciale a San Giuliano Milanese\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.investinitalyrealestate.com\/it\/#\/schema\/person\/d945b942fb6a7f2fa67a4689e376551d\",\"name\":\"Vittorio Zirnstein\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.investinitalyrealestate.com\/it\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/ad7d3442642427fe752c36c65c64655f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/ad7d3442642427fe752c36c65c64655f?s=96&d=mm&r=g\",\"caption\":\"Vittorio Zirnstein\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vitali inaugura nuovo parco commerciale a San Giuliano Milanese - ICE - Italian Trade Agency","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.investinitalyrealestate.com\/it\/vitali-inaugura-parco-commerciale-san-giuliano-milanese\/","og_locale":"it_IT","og_type":"article","og_title":"Vitali inaugura nuovo parco commerciale a San Giuliano Milanese - ICE - Italian Trade Agency","og_description":"Il Gruppo Vitali, primaria societ\u00e0 di costruzioni italiane, inaugura un nuovo parco commerciale a San Giuliano Milanese, nell&#8217;hinterland di Milano. L\u2019intervento si sviluppa su una superficie complessiva di oltre 20.000 mq ed \u00e8 stato costruito in tempi record, meno di 9 mesi dalla posa della prima pietra al taglio del nastro. Il nuovo parco commerciale [&hellip;]","og_url":"https:\/\/www.investinitalyrealestate.com\/it\/vitali-inaugura-parco-commerciale-san-giuliano-milanese\/","og_site_name":"ICE - Italian Trade Agency","article_published_time":"2016-12-02T08:00:44+00:00","article_modified_time":"2016-12-01T22:13:27+00:00","og_image":[{"width":1200,"height":628,"url":"https:\/\/www.investinitalyrealestate.com\/wp-content\/uploads\/2016\/02\/social-home.jpg","type":"image\/jpeg"}],"twitter_card":"summary","twitter_misc":{"Scritto da":"Vittorio Zirnstein"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/www.investinitalyrealestate.com\/it\/#website","url":"https:\/\/www.investinitalyrealestate.com\/it\/","name":"ICE - Italian Trade Agency","description":"Piattaforma per la vendita degli immobili pubblici Italiani","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.investinitalyrealestate.com\/it\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.investinitalyrealestate.com\/it\/vitali-inaugura-parco-commerciale-san-giuliano-milanese\/#webpage","url":"https:\/\/www.investinitalyrealestate.com\/it\/vitali-inaugura-parco-commerciale-san-giuliano-milanese\/","name":"Vitali inaugura nuovo parco commerciale a San Giuliano Milanese - ICE - Italian Trade Agency","isPartOf":{"@id":"https:\/\/www.investinitalyrealestate.com\/it\/#website"},"datePublished":"2016-12-02T08:00:44+00:00","dateModified":"2016-12-01T22:13:27+00:00","author":{"@id":"https:\/\/www.investinitalyrealestate.com\/it\/#\/schema\/person\/d945b942fb6a7f2fa67a4689e376551d"},"breadcrumb":{"@id":"https:\/\/www.investinitalyrealestate.com\/it\/vitali-inaugura-parco-commerciale-san-giuliano-milanese\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.investinitalyrealestate.com\/it\/vitali-inaugura-parco-commerciale-san-giuliano-milanese\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.investinitalyrealestate.com\/it\/vitali-inaugura-parco-commerciale-san-giuliano-milanese\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.investinitalyrealestate.com\/it\/"},{"@type":"ListItem","position":2,"name":"Vitali inaugura nuovo parco commerciale a San Giuliano Milanese"}]},{"@type":"Person","@id":"https:\/\/www.investinitalyrealestate.com\/it\/#\/schema\/person\/d945b942fb6a7f2fa67a4689e376551d","name":"Vittorio Zirnstein","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.investinitalyrealestate.com\/it\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/ad7d3442642427fe752c36c65c64655f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ad7d3442642427fe752c36c65c64655f?s=96&d=mm&r=g","caption":"Vittorio Zirnstein"}}]}},"wpml_current_locale":"it_IT","wpml_translations":[],"_links":{"self":[{"href":"https:\/\/www.investinitalyrealestate.com\/it\/wp-json\/wp\/v2\/posts\/16002"}],"collection":[{"href":"https:\/\/www.investinitalyrealestate.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.investinitalyrealestate.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.investinitalyrealestate.com\/it\/wp-json\/wp\/v2\/users\/462"}],"replies":[{"embeddable":true,"href":"https:\/\/www.investinitalyrealestate.com\/it\/wp-json\/wp\/v2\/comments?post=16002"}],"version-history":[{"count":1,"href":"https:\/\/www.investinitalyrealestate.com\/it\/wp-json\/wp\/v2\/posts\/16002\/revisions"}],"predecessor-version":[{"id":16003,"href":"https:\/\/www.investinitalyrealestate.com\/it\/wp-json\/wp\/v2\/posts\/16002\/revisions\/16003"}],"wp:attachment":[{"href":"https:\/\/www.investinitalyrealestate.com\/it\/wp-json\/wp\/v2\/media?parent=16002"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.investinitalyrealestate.com\/it\/wp-json\/wp\/v2\/categories?post=16002"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.investinitalyrealestate.com\/it\/wp-json\/wp\/v2\/tags?post=16002"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}